{"id":6,"date":"2019-09-19T21:29:02","date_gmt":"2019-09-19T21:29:02","guid":{"rendered":"https:\/\/qui.repaircom.nl\/index.php\/materialis\/"},"modified":"2020-05-31T11:29:43","modified_gmt":"2020-05-31T10:29:43","slug":"qcloud","status":"publish","type":"page","link":"https:\/\/qcloud.nu\/","title":{"rendered":"Qcloud"},"content":{"rendered":"<div  id=\"overlappable-8\" style=\"background-color: rgb(255, 255, 255); background-image: none;\" data-label=\"Overlappable\" data-id=\"overlappable-5-materialis\" data-export-id=\"overlappable-5-materialis\" data-category=\"overlappable\" class=\"overlappable-5-materialis content-section content-section-spacing-large\" data-overlap=\"true\">\n<div  class=\"\">\n<div  data-type=\"row\" class=\"row spaced-cols\">\n<div  class=\"col-xs-12 col-sm-6 col-md-6 \">\n<div  class=\"card mdc-elevation--z3 row-card\">\n<div  class=\"row\">\n<div  class=\"col-xs-12 col-sm-fit icon-col\" data-fixed=\"true\"><i  class=\"color1 icon mdi mdi-responsive reverse round big\"><\/i><\/div>\n<div  class=\"col-xs-12 col-sm\" data-type=\"column\">\n<h4  class=\"color-black\">OVERAL TOEGANG<\/h4>\n<p  class=\"\">Werk op uw desktop, laptop, smartphone of tablet.. <br >Waar ook ter wereld!<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-6 col-md-6 \">\n<div  class=\"card mdc-elevation--z3 row-card\">\n<div  class=\"row\">\n<div  class=\"col-xs-12 col-sm-fit icon-col\" data-fixed=\"true\"><i  class=\"color1 icon mdi mdi-security reverse round big\"><\/i><\/div>\n<div  class=\"col-xs-12 col-sm\" data-type=\"column\">\n<h4  class=\"color-black\">BEVEILIGDE VERBINDING<\/h4>\n<p  class=\"\">Dankzij de SSL verbinding met onze beveiligde server<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-6 col-md-6 \">\n<div  class=\"card mdc-elevation--z3 row-card\">\n<div  class=\"row\">\n<div  class=\"col-xs-12 col-sm-fit icon-col\" data-fixed=\"true\"><i  class=\"color1 icon mdi mdi-headset reverse round big\"><\/i><\/div>\n<div  class=\"col-xs-12 col-sm\" data-type=\"column\">\n<h4  class=\"color-black\">HELPDESK<\/h4>\n<p  class=\"\">Deskundige en persoonlijke helpdesk. \n<br >Bereikbaar via telefoon, WhatsApp of e-mail<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-6 col-md-6 \">\n<div  class=\"card mdc-elevation--z3 row-card\">\n<div  class=\"row\">\n<div  class=\"col-xs-12 col-sm-fit icon-col\" data-fixed=\"true\"><i  class=\"color1 icon mdi mdi-windows reverse round big\"><\/i><\/div>\n<div  class=\"col-xs-12 col-sm\" data-type=\"column\">\n<h4  class=\"color-black\">AL UW SOFTWARE BIJ DE HAND<\/h4>\n<p  class=\"\">Microsoft Office, Google Chrome&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"over\" style=\"background-color: rgb(245, 250, 253); background-image: none;\" data-label=\"About\" data-id=\"about-4\" data-export-id=\"about-4\" data-category=\"about\" class=\"about-4 content-section content-section-spacing-large\">\n<div  class=\"gridContainer\">\n<div  class=\"row middle-sm text-center\">\n<div  class=\"col-sm-5 space-bottom-xs\" data-type=\"column\">\n\n<h2  class=\"\">Al uw&nbsp;<br ><span  style=\"font-family: Playfair Display,sans-serif; font-weight: bold; font-style: italic;\" href=\"#\">programma\u2019s en bestanden<\/span> direct binnen handbereik<\/h2>\n\n<a class=\"button big color1 mdc-ripple-upgraded\" href=\"#abonnementen\" target=\"_self\" data-cp-link=\"1\" rel=\"noopener noreferrer\">BEKIJK DE TARIEVEN<\/a><\/div>\n<div  class=\"col-sm-7 flexbox center-xs middle-xs image-group-2-img padding-top-bottom\"><img decoding=\"async\"  class=\"img-1 rounded mdc-elevation--z10\" data-size=\"250x200\" src=\"https:\/\/qcloud.nu\/wp-content\/uploads\/2019\/09\/Windows_10_1903_Desktop.png\"> <img decoding=\"async\"  class=\"img-2 rounded mdc-elevation--z10\" data-size=\"220x170\" src=\"https:\/\/qcloud.nu\/wp-content\/uploads\/2019\/09\/Microsoft_Office_2019_-_Word_Excel_Outlook_PowerPoint.png\"><\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"voordelen\" style=\"background-color: rgb(255, 255, 255); background-image: none;\" data-label=\"Voordelen\" data-id=\"features-10-materialis\" data-export-id=\"features-10-materialis\" data-category=\"features\" class=\"features-10m content-section-spacing-large content-section\">\n<div  class=\"\">\n<div  class=\"row\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Waarom kiezen voor qCloud?<\/h2>\n<p  class=\"\">De voordelen op een rijtje<\/p>\n<\/div>\n<\/div>\n<div  class=\"row \">\n<div  class=\"col-xs-12 col-md-10 col-md-offset-1\">\n<div  class=\"row space-top spaced-cols content-center-sm\" data-type=\"row\" data-max-items=\"4\">\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-lock reverse round big\"><\/i>\n<h6  class=\"\">Volledig beveiligde verbinding<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-account-network reverse round big\"><\/i>\n<h6  class=\"\">Gepersonaliseerd profiel<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-apps reverse round big\"><\/i>\n<h6  class=\"\">Kant en \u2013 klare software<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-backup-restore reverse round big\"><\/i>\n<h6  class=\"\">Automatische back-ups<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-sm-offset-0 col-xs-10 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-office reverse round big\"><\/i>\n<h6  class=\"\">Office integratie<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-sm-offset-0 col-xs-10 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-arrow-up reverse round big\"><\/i>\n<h6  class=\"\">99,9% uptime<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-update reverse round big\"><\/i>\n<h6  class=\"\">Automatische updates<\/h6>\n<\/div>\n<\/div>\n<div  class=\"col-xs-10 col-sm-6 col-sm-offset-0 col-xs-offset-1 col-md-3 \">\n<div  class=\"card no-radius mdc-elevation--z1 y-move bg-color-white padding-24 bordered\" data-type=\"column\"><i  class=\"mdi icon color1 mdi-whatsapp reverse round big\"><\/i>\n<h6  class=\"\">Helpdesk bereikbaar via WhatsApp<\/h6>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div  data-label=\"Tarieven\" data-id=\"content--1\" data-export-id=\"content-5-materialis\" data-category=\"content\" class=\"content-5m content-section-spacing-large content-section\" id=\"tarieven\" style=\"background-color: #f5fafd;\">\n<div  class=\"gridContainer\">\n<div  class=\"row\">\n<div  class=\"col-xs-12 col-sm-8 col-sm-offset-2 space-bottom text-center col-padding-small-xs\" data-type=\"column\"><\/div>\n<div  class=\"col-xs-12 text-center large\" data-type=\"column\">\n<h2  class=\"space-bottom\">Tarieven<\/h2>\n<p  class=\"lead\">Prijzen zijn exclusief 21% BTW, per maand<\/p>\n<p  class=\"\">\n\n<\/p>\n<!-- appts-table-wrapper -->    \n        \n    \n\n\n<!-- appts-table-wrapper -->    \n        \n    \n\n\n<!-- appts-table-wrapper -->    \n        \n    \n\n<p  class=\"\">Exclusief \u20ac 75,00 licentiekosten per gebruiker, per maand<\/p>\n<!-- appts-table-wrapper -->    \n        \n    \n\n\n<!-- appts-table-wrapper -->    \n        \n     \n\n\n<!-- appts-table-wrapper -->    \n        \n    \n<!-- appts-table-wrapper -->\n<div  class=\"\"><\/div>\n<a class=\"button color1 big mdc-elevation--z3 mdc-ripple-upgraded\" href=\"#contact-1\" target=\"_self\" data-cp-link=\"1\" rel=\"noopener noreferrer\">CONTACT OPNEMEN<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><!-- CloudPress Companion Preview Data START --><!-- CloudPress Companion Preview Data START --><div  id=\"contact-1\" data-label=\"Contact\" data-id=\"contact-1\" data-export-id=\"contact-1\" data-category=\"contact\" class=\"contact-1 content-section content-section-spacing-large content-relative white-text\" data-parallax-depth=\"20\" style=\"background-size: cover; background-position: center top; background-image: url('https:\/\/qcloud.nu\/wp-content\/uploads\/2019\/09\/sky-1441936_1920.jpg');\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Contact<\/h2>\n<p  class=\"lead\">Heeft u nog vragen over onze qCloud service? <br >Vul hieronder het contactformulier in<\/p>\n<\/div>\n<\/div>\n<div  class=\"row text-center\">\n<div  class=\"col-xs-12 col-sm-8 col-sm-offset-2 contact-form-wrapper\">\n<div  class=\"card mdc-elevation--z3 col-padding-top\">\n<div  class=\"dark-text\" data-content-shortcode=\"materialis_contact_form shortcode=&quot;contact-form-7 id=&amp;amp;quot;8&amp;amp;quot; title=&amp;amp;quot;Contactformulier 1&amp;amp;quot;&quot;\" data-editable=\"true\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8-o1\" lang=\"nl-NL\" dir=\"ltr\" data-wpcf7-id=\"8\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/6#wpcf7-f8-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"nl_NL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Je naam (verplicht)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Je e-mailadres (verplicht)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Onderwerp<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Je bericht<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Verzenden\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage.php","meta":{"footnotes":""},"class_list":["post-6","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":112,"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":312,"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/pages\/6\/revisions\/312"}],"wp:attachment":[{"href":"https:\/\/qcloud.nu\/index.php\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}